{"id":16238,"date":"2022-12-19T23:03:05","date_gmt":"2022-12-20T02:03:05","guid":{"rendered":"https:\/\/municipales.org.ar\/festram\/?p=16238"},"modified":"2023-02-08T19:51:05","modified_gmt":"2023-02-08T22:51:05","slug":"festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre","status":"publish","type":"post","link":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/","title":{"rendered":"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">QUE SE RESPETE LA LEGISLACI\u00d3N VIGENTE<br><\/h2>\n\n\n\n<p>Frente a las comunicaciones del Gobierno de la Provincia de Santa Fe por distintos medios, informando que la Provincia no adhiere al Decreto del Gobierno Nacional por el cual se establece Feriado Nacional para el d\u00eda 20 de Diciembre en todo el pa\u00eds, la Federaci\u00f3n de Sindicatos de Trabajadores Municipales de la Provincia de Santa Fe, desea comunicar lo siguiente:<\/p>\n\n\n\n<p>Un Decreto del Presidente de la Naci\u00f3n en uso de sus facultades tiene prevalencia normativa a cualquiera otra disposici\u00f3n de car\u00e1cter provincial; existe una clara jerarquizaci\u00f3n que el Ejecutivo Provincial est\u00e1 pretendiendo desconocer.<\/p>\n\n\n\n<p>En este caso dicho DNU expresa de manera contundente en su art\u00edculo Primero lo siguiente: \u201cDecl\u00e1rase feriado nacional el d\u00eda 20 de diciembre de 2022 con el fin de que el pueblo argentino pueda festejar y compartir con la SELECCI\u00d3N MASCULINA ARGENTINA DE F\u00daTBOL el t\u00edtulo de Campeones Mundiales de F\u00fatbol obtenido en la \u201cCopa Mundial de la FIFA CATAR 2022\u201d.<\/p>\n\n\n\n<p>El mismo no hace distinciones territoriales ni de los sectores de trabajadorxs que quedan comprendidos, situaci\u00f3n \u00e9sta que es expl\u00edcita cuando se\u00f1ala las excepciones horarias en la AFIP y los bancos en general sin establecer si son p\u00fablicos o privados, por lo tanto se est\u00e1 incurriendo en el error de confundir los alcances de un feriado nacional con un asueto.<\/p>\n\n\n\n<p><strong>Legalmente, corresponde que aquellos trabajadorxs que fueran convocados a cumplir las tareas habituales el d\u00eda 20 de Diciembre, seg\u00fan la legislaci\u00f3n respectiva, se le debe pagar doble.<\/strong><\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><br>Prensa FESTRAM<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Que se respete la legislaci\u00f3n vigente<\/p>\n","protected":false},"author":1,"featured_media":16240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[241],"tags":[70,109],"class_list":["post-16238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados-2022","tag-el-pais","tag-la-provincia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre &#8211; FESTRAM<\/title>\n<meta name=\"description\" content=\"Que se respete la legislaci\u00f3n vigente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre &#8211; FESTRAM\" \/>\n<meta property=\"og:description\" content=\"Que se respete la legislaci\u00f3n vigente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/\" \/>\n<meta property=\"og:site_name\" content=\"FESTRAM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MunicipalesSF\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-20T02:03:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T22:51:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mun_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MunicipalesSF\" \/>\n<meta name=\"twitter:site\" content=\"@MunicipalesSF\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mun_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/\"},\"author\":{\"name\":\"mun_admin\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/#\/schema\/person\/49096a774c48ce9063df4d59ec059f9e\"},\"headline\":\"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre\",\"datePublished\":\"2022-12-20T02:03:05+00:00\",\"dateModified\":\"2023-02-08T22:51:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/\"},\"wordCount\":277,\"publisher\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/#organization\"},\"image\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg\",\"keywords\":[\"el pa\u00eds\",\"la provincia\"],\"articleSection\":[\"Comunicados 2022\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/\",\"url\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/\",\"name\":\"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre &#8211; FESTRAM\",\"isPartOf\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg\",\"datePublished\":\"2022-12-20T02:03:05+00:00\",\"dateModified\":\"2023-02-08T22:51:05+00:00\",\"description\":\"Que se respete la legislaci\u00f3n vigente\",\"breadcrumb\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#primaryimage\",\"url\":\"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg\",\"contentUrl\":\"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/municipales.org.ar\/festram\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/#website\",\"url\":\"https:\/\/municipales.org.ar\/festram\/\",\"name\":\"FESTRAM\",\"description\":\"La web de los trabajadores municipales\",\"publisher\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/municipales.org.ar\/festram\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/#organization\",\"name\":\"Federaci\u00f3n de Sindicatos de Trabajadores Municipales de la Provincia de Santa Fe\",\"url\":\"https:\/\/municipales.org.ar\/festram\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.municipales.org.ar\/festram\/wp-content\/uploads\/2014\/07\/logo_fes.jpg\",\"contentUrl\":\"https:\/\/www.municipales.org.ar\/festram\/wp-content\/uploads\/2014\/07\/logo_fes.jpg\",\"width\":661,\"height\":673,\"caption\":\"Federaci\u00f3n de Sindicatos de Trabajadores Municipales de la Provincia de Santa Fe\"},\"image\":{\"@id\":\"https:\/\/municipales.org.ar\/festram\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MunicipalesSF\",\"https:\/\/x.com\/MunicipalesSF\",\"https:\/\/www.youtube.com\/user\/festram\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/municipales.org.ar\/festram\/#\/schema\/person\/49096a774c48ce9063df4d59ec059f9e\",\"name\":\"mun_admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre &#8211; FESTRAM","description":"Que se respete la legislaci\u00f3n vigente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/","og_locale":"es_ES","og_type":"article","og_title":"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre &#8211; FESTRAM","og_description":"Que se respete la legislaci\u00f3n vigente","og_url":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/","og_site_name":"FESTRAM","article_publisher":"https:\/\/www.facebook.com\/MunicipalesSF","article_published_time":"2022-12-20T02:03:05+00:00","article_modified_time":"2023-02-08T22:51:05+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg","type":"image\/jpeg"}],"author":"mun_admin","twitter_card":"summary_large_image","twitter_creator":"@MunicipalesSF","twitter_site":"@MunicipalesSF","twitter_misc":{"Escrito por":"mun_admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#article","isPartOf":{"@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/"},"author":{"name":"mun_admin","@id":"https:\/\/municipales.org.ar\/festram\/#\/schema\/person\/49096a774c48ce9063df4d59ec059f9e"},"headline":"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre","datePublished":"2022-12-20T02:03:05+00:00","dateModified":"2023-02-08T22:51:05+00:00","mainEntityOfPage":{"@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/"},"wordCount":277,"publisher":{"@id":"https:\/\/municipales.org.ar\/festram\/#organization"},"image":{"@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg","keywords":["el pa\u00eds","la provincia"],"articleSection":["Comunicados 2022"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/","url":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/","name":"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre &#8211; FESTRAM","isPartOf":{"@id":"https:\/\/municipales.org.ar\/festram\/#website"},"primaryImageOfPage":{"@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#primaryimage"},"image":{"@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg","datePublished":"2022-12-20T02:03:05+00:00","dateModified":"2023-02-08T22:51:05+00:00","description":"Que se respete la legislaci\u00f3n vigente","breadcrumb":{"@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#primaryimage","url":"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg","contentUrl":"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/municipales.org.ar\/festram\/festram-aclara-sobre-el-feriado-nacional-del-dia-20-de-diciembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/municipales.org.ar\/festram\/"},{"@type":"ListItem","position":2,"name":"FESTRAM aclara sobre el Feriado Nacional del d\u00eda 20 de Diciembre"}]},{"@type":"WebSite","@id":"https:\/\/municipales.org.ar\/festram\/#website","url":"https:\/\/municipales.org.ar\/festram\/","name":"FESTRAM","description":"La web de los trabajadores municipales","publisher":{"@id":"https:\/\/municipales.org.ar\/festram\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/municipales.org.ar\/festram\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/municipales.org.ar\/festram\/#organization","name":"Federaci\u00f3n de Sindicatos de Trabajadores Municipales de la Provincia de Santa Fe","url":"https:\/\/municipales.org.ar\/festram\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/municipales.org.ar\/festram\/#\/schema\/logo\/image\/","url":"https:\/\/www.municipales.org.ar\/festram\/wp-content\/uploads\/2014\/07\/logo_fes.jpg","contentUrl":"https:\/\/www.municipales.org.ar\/festram\/wp-content\/uploads\/2014\/07\/logo_fes.jpg","width":661,"height":673,"caption":"Federaci\u00f3n de Sindicatos de Trabajadores Municipales de la Provincia de Santa Fe"},"image":{"@id":"https:\/\/municipales.org.ar\/festram\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MunicipalesSF","https:\/\/x.com\/MunicipalesSF","https:\/\/www.youtube.com\/user\/festram"]},{"@type":"Person","@id":"https:\/\/municipales.org.ar\/festram\/#\/schema\/person\/49096a774c48ce9063df4d59ec059f9e","name":"mun_admin"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/municipales.org.ar\/festram\/wp-content\/uploads\/2022\/12\/casarosada.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/p7l4x1-4dU","_links":{"self":[{"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/posts\/16238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/comments?post=16238"}],"version-history":[{"count":2,"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/posts\/16238\/revisions"}],"predecessor-version":[{"id":16243,"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/posts\/16238\/revisions\/16243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/media\/16240"}],"wp:attachment":[{"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/media?parent=16238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/categories?post=16238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/municipales.org.ar\/festram\/wp-json\/wp\/v2\/tags?post=16238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}